{"id":1992,"date":"2025-11-06T11:14:26","date_gmt":"2025-11-06T11:14:26","guid":{"rendered":"https:\/\/riftgame.com\/?p=1992"},"modified":"2025-11-06T11:14:26","modified_gmt":"2025-11-06T11:14:26","slug":"mech-parade-3","status":"publish","type":"post","link":"https:\/\/riftgame.com\/de\/2025\/11\/06\/mech-parade-3\/","title":{"rendered":"Mech-Parade!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hallo Aufgestiegene!<br>Blitze sind in ganz Telara zu h\u00f6ren, und die Mechs sind zur\u00fcck, bringen die Erde zum Beben und stiften Chaos, wo immer sie auftauchen! Werdet ihr helfen, Telara gegen diese schwer gepanzerten Feinde zu verteidigen?<br><br>Genau das haben wir uns gedacht, Aufgestiegene. Sch\u00e4rft euer Schwert und eure Sinne und schlagt jetzt zur\u00fcck! Ab heute k\u00f6nnt ihr die Mechs belagern, um euch tolle Belohnungen zu verdienen!<br><br>Begebt euch nach Sanctum (\/setwaypoint 7380 3077), Meridian (\/setwaypoint 6124 5231) oder zur Sturmbucht (\/setwaypoint 12944 11579), um t\u00e4gliche Quests anzunehmen und an Kriegsfronten teilzunehmen. Nutzt das Looking For Group (LFG)-Tool, um an Experten-Dungeons teilzunehmen, Mech-Komponenten zu sammeln oder am Zonen-Event teilzunehmen!<br><br>Wenn du alle t\u00e4glichen Quests abschlie\u00dft, erh\u00e4ltst du jeden Tag insgesamt 65 Chaospartikel pro Charakter!<br><br>Die Quest \u201cVerteidiger der Elemente\u201d f\u00fchrt euch nach Vostigar Gipfel, Silberwald, Freimark, Schimmersand und Stillmoor, wo ihr furchterregende Mechs besiegen m\u00fcsst.<br><br>Bleibt wachsam und bringt eure Verb\u00fcndeten mit, Aufgestiegene; ihr k\u00f6nnt sie jetzt mehr denn je brauchen!<br><br><img decoding=\"async\" src=\"https:\/\/clan.akamai.steamstatic.com\/images\/\/2480908\/68cc6bc3c3889101281d551c0c28bf9f5fcfc017.png\"><br><br>Besucht den RIFT-Store, um Belohnungen f\u00fcr Credits zu erhalten, oder benutzt eure gesammelten Chaospartikel beim Event-NPC, um erstaunliche Reittiere, Belohnungen, Haustiere und vieles mehr einzul\u00f6sen!<br><br><img decoding=\"async\" src=\"https:\/\/clan.akamai.steamstatic.com\/images\/\/2480908\/0824ead0de9fe3b79faa59cc6d4295219e0252bd.png\">\u00a0<br><br>Jetzt ist es an der Zeit zuzuschlagen, Aufgestiegene. Die Mechs werden am\u00a0<strong>7. November 2025<\/strong>\u00a0zuschlagen und sich am<strong> 11. November 2025, 23:59 UTC<\/strong>\u00a0zur\u00fcckziehen; haltet sie bis dahin in Schach, bevor sie zu viel Schaden anrichten!<br><br>Wir sehen uns im Spiel,<br>Euer RIFT-Team!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hallo Aufgestiegene!Blitze sind in ganz Telara zu h\u00f6ren, und die Mechs sind zur\u00fcck, bringen die Erde zum Beben und stiften Chaos, wo immer sie auftauchen! Werdet ihr helfen, Telara gegen diese schwer gepanzerten Feinde zu verteidigen? Genau das haben wir uns gedacht, Aufgestiegene. Sch\u00e4rft euer Schwert und eure Sinne und schlagt jetzt zur\u00fcck! Ab heute [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":1991,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[54,27],"tags":[],"class_list":["post-1992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events-de","category-neuigkeiten"],"acf":[],"_links":{"self":[{"href":"https:\/\/riftgame.com\/de\/wp-json\/wp\/v2\/posts\/1992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riftgame.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/riftgame.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/riftgame.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/riftgame.com\/de\/wp-json\/wp\/v2\/comments?post=1992"}],"version-history":[{"count":0,"href":"https:\/\/riftgame.com\/de\/wp-json\/wp\/v2\/posts\/1992\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/riftgame.com\/de\/wp-json\/wp\/v2\/media\/1991"}],"wp:attachment":[{"href":"https:\/\/riftgame.com\/de\/wp-json\/wp\/v2\/media?parent=1992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/riftgame.com\/de\/wp-json\/wp\/v2\/categories?post=1992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/riftgame.com\/de\/wp-json\/wp\/v2\/tags?post=1992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}